{"id":8960,"date":"2023-01-05T16:11:15","date_gmt":"2023-01-05T08:11:15","guid":{"rendered":"https:\/\/saltcreatives.com\/saltees\/?post_type=product&#038;p=8960"},"modified":"2023-08-03T16:07:28","modified_gmt":"2023-08-03T08:07:28","slug":"progress-colour","status":"publish","type":"product","link":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/","title":{"rendered":"Progress (Colour)"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<strong>About the Design<\/strong><\/p>\n<p>Specially created for 2023 rabbit year, the CNY 2023 Progress series plays on the term &#8220;<span lang=\"ZH-CN\">\u7a81\u98de\u731b\u8fdb<\/span>&#8221; \u2013 which literally means to advance by leaps and bounds \u2013 and replaces the first word with\u00a0<span lang=\"ZH-CN\">&#8220;\u5154&#8221;<\/span><span lang=\"ZH-CN\">\u00a0<\/span>(rabbit) to symbolise the rabbit year. May you leap to further heights in the new year![\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]About the Design Specially created for 2023 rabbit year, the CNY 2023 Progress series plays on the term &#8220;\u7a81\u98de\u731b\u8fdb&#8221; \u2013 which literally means to advance&#8230;<\/p>\n","protected":false},"featured_media":8969,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[144],"product_tag":[],"class_list":{"0":"post-8960","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cny-2023-series","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable","14":"has-default-attributes"},"etheme_brands":{"errors":{"invalid_taxonomy":["Invalid taxonomy."]},"error_data":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Progress (Colour) - Saltees<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progress (Colour) - Saltees\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]About the Design Specially created for 2023 rabbit year, the CNY 2023 Progress series plays on the term &#8220;\u7a81\u98de\u731b\u8fdb&#8221; \u2013 which literally means to advance...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/\" \/>\n<meta property=\"og:site_name\" content=\"Saltees\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-03T08:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/saltcreatives.com\/saltees\/wp-content\/uploads\/2023\/01\/Saltees_CNY_Rabbit_Maroon_Colour-800x800.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/product\\\/progress-colour\\\/\",\"url\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/product\\\/progress-colour\\\/\",\"name\":\"Progress (Colour) - Saltees\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/product\\\/progress-colour\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/product\\\/progress-colour\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Saltees_CNY_Rabbit_Maroon_Colour.jpg\",\"datePublished\":\"2023-01-05T08:11:15+00:00\",\"dateModified\":\"2023-08-03T08:07:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/product\\\/progress-colour\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/product\\\/progress-colour\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/product\\\/progress-colour\\\/#primaryimage\",\"url\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Saltees_CNY_Rabbit_Maroon_Colour.jpg\",\"contentUrl\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Saltees_CNY_Rabbit_Maroon_Colour.jpg\",\"width\":3000,\"height\":3000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/product\\\/progress-colour\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Progress (Colour)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/#website\",\"url\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/\",\"name\":\"Saltees\",\"description\":\"An exciting contemporary brand which focuses on high-quality products\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/saltcreatives.com\\\/saltees\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progress (Colour) - Saltees","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/","og_locale":"en_US","og_type":"article","og_title":"Progress (Colour) - Saltees","og_description":"[vc_row][vc_column][vc_column_text]About the Design Specially created for 2023 rabbit year, the CNY 2023 Progress series plays on the term &#8220;\u7a81\u98de\u731b\u8fdb&#8221; \u2013 which literally means to advance...","og_url":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/","og_site_name":"Saltees","article_modified_time":"2023-08-03T08:07:28+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/saltcreatives.com\/saltees\/wp-content\/uploads\/2023\/01\/Saltees_CNY_Rabbit_Maroon_Colour-800x800.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/","url":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/","name":"Progress (Colour) - Saltees","isPartOf":{"@id":"https:\/\/saltcreatives.com\/saltees\/#website"},"primaryImageOfPage":{"@id":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/#primaryimage"},"image":{"@id":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/#primaryimage"},"thumbnailUrl":"https:\/\/saltcreatives.com\/saltees\/wp-content\/uploads\/2023\/01\/Saltees_CNY_Rabbit_Maroon_Colour.jpg","datePublished":"2023-01-05T08:11:15+00:00","dateModified":"2023-08-03T08:07:28+00:00","breadcrumb":{"@id":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/#primaryimage","url":"https:\/\/saltcreatives.com\/saltees\/wp-content\/uploads\/2023\/01\/Saltees_CNY_Rabbit_Maroon_Colour.jpg","contentUrl":"https:\/\/saltcreatives.com\/saltees\/wp-content\/uploads\/2023\/01\/Saltees_CNY_Rabbit_Maroon_Colour.jpg","width":3000,"height":3000},{"@type":"BreadcrumbList","@id":"https:\/\/saltcreatives.com\/saltees\/product\/progress-colour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/saltcreatives.com\/saltees\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/saltcreatives.com\/saltees\/"},{"@type":"ListItem","position":3,"name":"Progress (Colour)"}]},{"@type":"WebSite","@id":"https:\/\/saltcreatives.com\/saltees\/#website","url":"https:\/\/saltcreatives.com\/saltees\/","name":"Saltees","description":"An exciting contemporary brand which focuses on high-quality products","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/saltcreatives.com\/saltees\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/product\/8960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/comments?post=8960"}],"version-history":[{"count":1,"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/product\/8960\/revisions"}],"predecessor-version":[{"id":9209,"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/product\/8960\/revisions\/9209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/media\/8969"}],"wp:attachment":[{"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/media?parent=8960"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/product_brand?post=8960"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/product_cat?post=8960"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/saltcreatives.com\/saltees\/wp-json\/wp\/v2\/product_tag?post=8960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}